{"id":4447,"date":"2020-08-11T11:04:19","date_gmt":"2020-08-11T11:04:19","guid":{"rendered":"http:\/\/wpdemo.archiwp.com\/theratio\/?page_id=4447"},"modified":"2023-12-26T20:00:16","modified_gmt":"2023-12-26T20:00:16","slug":"one-page","status":"publish","type":"page","link":"https:\/\/isafetyengenharia.com\/home\/","title":{"rendered":"iSatefy Engenharia"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4447\" class=\"elementor elementor-4447\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-23fb6ca elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"23fb6ca\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8f524b5\" data-id=\"8f524b5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c031453 elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"c031453\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-174feb4 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg elementor-ken-burns elementor-ken-burns--in\" role=\"img\" aria-label=\"base de imagens para site RI - 30\"><\/div><div class=\"elementor-background-overlay\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/isafetyengenharia.com\/home\/servicos-2\/\" target=\"_blank\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Engenharia de Seguran\u00e7a do Trabalho<\/div><div class=\"elementor-slide-description\">Engenharia a Servi\u00e7o da Vida<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">Ver servi\u00e7os<\/div><\/div><\/a><\/div><div class=\"elementor-repeater-item-3ba72fd swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg elementor-ken-burns elementor-ken-burns--in\" role=\"img\" aria-label=\"base de imagens para site RI - 32\"><\/div><div class=\"elementor-background-overlay\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Meio Ambiente<\/div><div class=\"elementor-slide-description\">Especialistas em projetos de meio ambiente.<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">Ver servi\u00e7os<\/div><\/div><\/div><\/div><div class=\"elementor-repeater-item-eadd9d8 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg elementor-ken-burns elementor-ken-burns--in\" role=\"img\" aria-label=\"base de imagens para site RI - 34\"><\/div><div class=\"elementor-background-overlay\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Treinamentos <\/div><div class=\"elementor-slide-description\">Treinamentos T\u00e9cnicos e normativos de qualidade.<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">Ver servi\u00e7os<\/div><\/div><\/div><\/div><div class=\"elementor-repeater-item-a5e91bf swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg elementor-ken-burns elementor-ken-burns--in\" role=\"img\" aria-label=\"base de imagens para site RI - 33\"><\/div><div class=\"elementor-background-overlay\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Drone Specialist<\/div><div class=\"elementor-slide-description\">Utiliza\u00e7\u00e3o de drones para fiscaliza\u00e7\u00e3o e monitoramentos de projetos e empresas.<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">Ver servi\u00e7os<\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Slide anterior\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Pr\u00f3ximo slide\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f280a38 elementor-section-full_width elementor-section-height-full elementor-section-content-middle elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-height-default elementor-section-items-middle\" data-id=\"f280a38\" data-element_type=\"section\" data-e-type=\"section\" id=\"home\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_link&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=Npy9rAk-92w&quot;,&quot;background_video_start&quot;:1,&quot;background_video_end&quot;:37,&quot;background_play_on_mobile&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-background-video-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-background-video-embed\" role=\"presentation\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2ef3c9f\" data-id=\"2ef3c9f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7532ba5 elementor-widget elementor-widget-image\" data-id=\"7532ba5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/elementor\/thumbs\/ISAFETY-LOGO-NOVO-co\u0301pia-ovi7j82zfn6n456lec7f8uvyeg1rl18smyg9oczcp2.png\" title=\"ISAFETY-LOGO \u2013 NOVO co\u0301pia\" alt=\"ISAFETY-LOGO - NOVO co\u0301pia\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4ca6fd4 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4ca6fd4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9291515\" data-id=\"9291515\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d2902b3 elementor-widget elementor-widget-image\" data-id=\"d2902b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/10\/85bba809-29ba-455d-aefe-a0739ab17273-1024x1024.jpg\" class=\"attachment-large size-large wp-image-5479\" alt=\"\" srcset=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/10\/85bba809-29ba-455d-aefe-a0739ab17273-1024x1024.jpg 1024w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/10\/85bba809-29ba-455d-aefe-a0739ab17273-300x300.jpg 300w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/10\/85bba809-29ba-455d-aefe-a0739ab17273-150x150.jpg 150w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/10\/85bba809-29ba-455d-aefe-a0739ab17273-768x768.jpg 768w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/10\/85bba809-29ba-455d-aefe-a0739ab17273.jpg 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ffdfde0 elementor-cta--skin-cover elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"ffdfde0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"https:\/\/api.whatsapp.com\/send\/?phone=5512997613782&#038;text=OL%C3%81.+Estava+navegando+em+seu+site+iSafety+Engenharia+e+gostaria+de+mais+informa%C3%A7%C3%B5es.&#038;type=phone_number&#038;app_absent=0\" target=\"_blank\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url();\" role=\"img\" aria-label=\"\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tN\u00d3S CUIDAMOS DA SUA SEGURAN\u00c7A NO TRABALHO\u200b\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tAtuamos em diversos segmentos, como obras, empresas, \u00e1reas rurais, etc.\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t<span class=\"elementor-cta__button elementor-button elementor-size-\">\n\t\t\t\t\t\tSAIBA MAIS\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-69e3637\" data-id=\"69e3637\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3fe9f08 elementor-widget elementor-widget-image\" data-id=\"3fe9f08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/10\/7ea0a6b2-2ce2-454d-a162-96f7541f98de-1024x1024.jpg\" class=\"attachment-large size-large wp-image-5478\" alt=\"\" srcset=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/10\/7ea0a6b2-2ce2-454d-a162-96f7541f98de-1024x1024.jpg 1024w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/10\/7ea0a6b2-2ce2-454d-a162-96f7541f98de-300x300.jpg 300w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/10\/7ea0a6b2-2ce2-454d-a162-96f7541f98de-150x150.jpg 150w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/10\/7ea0a6b2-2ce2-454d-a162-96f7541f98de-768x768.jpg 768w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/10\/7ea0a6b2-2ce2-454d-a162-96f7541f98de.jpg 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9dcca0d elementor-cta--skin-cover elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"9dcca0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"https:\/\/api.whatsapp.com\/send\/?phone=5512997613782&#038;text=OL%C3%81.+Estava+navegando+em+seu+site+iSafety+Engenharia+e+gostaria+de+mais+informa%C3%A7%C3%B5es.&#038;type=phone_number&#038;app_absent=0\" target=\"_blank\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url();\" role=\"img\" aria-label=\"\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tCUIDAMOS DA SUA PER\u00cdCIA JUDICIAL\u200b\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tPeritos cadastrados e certificados pelo Conselho Nacional de Peritos Judiciais\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t<span class=\"elementor-cta__button elementor-button elementor-size-\">\n\t\t\t\t\t\tSAIBA MAIS\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d068981 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d068981\" data-element_type=\"section\" data-e-type=\"section\" id=\"inicio\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-55ef304\" data-id=\"55ef304\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-24fb8ec elementor-cta--skin-cover elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"24fb8ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url();\" role=\"img\" aria-label=\"\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tREGULARIZAMOS SUA EDIFICA\u00c7\u00c3O\u200b\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tObten\u00e7\u00e3o ou regulariza\u00e7\u00e3o de AVCB - CLCB Certificado de Licen\u00e7a do Corpo de Bombeiros\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\" href=\"https:\/\/isafetyengenharia.com\/home\/bombeiros\/\" target=\"_blank\">\n\t\t\t\t\t\tSAIBA MAIS\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-cc88d89\" data-id=\"cc88d89\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b4bec9 elementor-cta--skin-cover elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"7b4bec9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url();\" role=\"img\" aria-label=\"\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tTREINAMOS SUA EQUIPE NOS PRINCIPAIS CURSOS\u200b\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tNR35 - NR33 - NR23 - NR20 - NR18 - NR12 - NR13 - NR11 - NR10 - NR9 - NR6 - NR5 - CIPA, etc.\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\" href=\"https:\/\/isafetyengenharia.com\/home\/treinamentos\/\" target=\"_blank\">\n\t\t\t\t\t\tSAIBA MAIS\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-31fa17d elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"31fa17d\" data-element_type=\"section\" data-e-type=\"section\" id=\"drone\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6357e47\" data-id=\"6357e47\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3198fbd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3198fbd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-55f7816\" data-id=\"55f7816\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a70477c elementor-cta--skin-cover elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"a70477c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/09\/drone-construcao-civil1-1024x470.jpeg);\" role=\"img\" aria-label=\"Constru\u00e7\u00e3o civil\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tCONSTRU\u00c7\u00c3O CIVIL\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tIMAGENS \u00c1REAS DE SUA OBRA\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\" href=\"https:\/\/isafetyengenharia.com\/home\/drone\/\" target=\"_blank\">\n\t\t\t\t\t\tSAIBA MAIS\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a96e9b5\" data-id=\"a96e9b5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b73f2c elementor-cta--skin-cover elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"4b73f2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/09\/drone-eventos1.jpg);\" role=\"img\" aria-label=\"Eventos\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tEVENTOS\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tIMAGENS A\u00c9REAS DO SEU EVENTO\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\" href=\"https:\/\/isafetyengenharia.com\/home\/drone\/\" target=\"_blank\">\n\t\t\t\t\t\tSAIBA MAIS\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-352db4d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"352db4d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b09a311\" data-id=\"b09a311\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-518f53a elementor-cta--skin-cover elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"518f53a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/09\/drone-mercado-imobiliario.jpg);\" role=\"img\" aria-label=\"Mercado Imobili\u00e1rio\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tMERCADO IMOBILI\u00c1RIO\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tIMAGENS \u00c1REAS DE LOETAMENTOS E \u00c1REAS RURAIS\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\" href=\"https:\/\/isafetyengenharia.com\/home\/drone\/\" target=\"_blank\">\n\t\t\t\t\t\tSAIBA MAIS\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-bfe770b\" data-id=\"bfe770b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29dc0f8 elementor-cta--skin-cover elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"29dc0f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/09\/industria-drone.jpg);\" role=\"img\" aria-label=\"Industrias\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tIND\u00daSTRIAS\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tIMAGENS A\u00c9REAS DE SUA EMPRESA OU ORGANIZA\u00c7\u00c3O\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\" href=\"https:\/\/isafetyengenharia.com\/home\/drone\/\" target=\"_blank\">\n\t\t\t\t\t\tSAIBA MAIS\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-606904c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"606904c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-389b4b8\" data-id=\"389b4b8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65e71c4 elementor-widget elementor-widget-heading\" data-id=\"65e71c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Sobre<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9d286df elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9d286df\" data-element_type=\"section\" data-e-type=\"section\" id=\"sobre\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-60ca5b7\" data-id=\"60ca5b7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b1a516 elementor-widget elementor-widget-image\" data-id=\"4b1a516\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/10\/a05b73d6-2e29-4c6c-8d0e-10ec24588013-1024x1024.jpg\" class=\"attachment-large size-large wp-image-5471\" alt=\"\" srcset=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/10\/a05b73d6-2e29-4c6c-8d0e-10ec24588013-1024x1024.jpg 1024w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/10\/a05b73d6-2e29-4c6c-8d0e-10ec24588013-300x300.jpg 300w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/10\/a05b73d6-2e29-4c6c-8d0e-10ec24588013-150x150.jpg 150w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/10\/a05b73d6-2e29-4c6c-8d0e-10ec24588013-768x768.jpg 768w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/10\/a05b73d6-2e29-4c6c-8d0e-10ec24588013.jpg 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e6fc4e content-align-cta-center elementor-widget elementor-widget-eael-cta-box\" data-id=\"6e6fc4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-cta-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"eael-call-to-action cta-basic bg-lite cta-preset-1\">\n        <h2 class=\"title eael-cta-heading\">Entre em contato<\/h2><p style=\"text-align: left\">E saiba como podemos fortalecer a seguran\u00e7a em sua empresa e proteger seus ativos mais valiosos: <strong>seus colaboradores.<\/strong><\/p><a href=\"https:\/\/api.whatsapp.com\/send\/?phone=5512997613782&#038;text=OL%C3%81.+Estava+navegando+em+seu+site+iSafety+Engenharia+e+gostaria+de+mais+informa%C3%A7%C3%B5es.&#038;type=phone_number&#038;app_absent=0\" class=\"cta-button cta-preset-1  effect-1\">Contato<\/a>\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8f22ad4\" data-id=\"8f22ad4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f81363 elementor-widget elementor-widget-text-editor\" data-id=\"2f81363\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bem-vindo \u00e0 <strong>iSafety Engenharia<\/strong>, sua parceira confi\u00e1vel em Seguran\u00e7a do Trabalho e Sa\u00fade Ocupacional. Na iSafety, entendemos que seu maior ativo \u00e9 sua equipe, e estamos comprometidos em garantir a prote\u00e7\u00e3o e o bem-estar de cada membro dela.<\/p><p><strong>Nossa miss\u00e3o \u00e9 clara:<\/strong> proporcionar um ambiente de trabalho seguro para que sua empresa e seus colaboradores prosperem. Com anos de experi\u00eancia e conhecimento especializado em Seguran\u00e7a do Trabalho, somos a escolha ideal para auxili\u00e1-lo na busca de excel\u00eancia em seguran\u00e7a ocupacional.<\/p><p style=\"text-align: center;\"><strong>O que estamos oferecendo:<\/strong><\/p><p>Avalia\u00e7\u00e3o de Riscos Ocupacionais : Realizamos avalia\u00e7\u00f5es completas e personalizadas para identificar riscos espec\u00edficos \u00e0 sua ind\u00fastria e local de trabalho, garantindo que todos os perigos sejam identificados e minimizados.<\/p><p>Desenvolvimento de Programas de Seguran\u00e7a : Criamos programas de seguran\u00e7a sob medida para atender \u00e0s necessidades de sua empresa, incluindo treinamentos, pol\u00edticas e procedimentos de seguran\u00e7a.<\/p><p>Treinamento Especializado : Nossos instrutores altamente especializados oferecem treinamento pr\u00e1tico e te\u00f3rico em quest\u00f5es de seguran\u00e7a, capacitando seus funcion\u00e1rios a agirem de maneira segura em todas as situa\u00e7\u00f5es.<\/p><p>Gest\u00e3o de Conformidade : Acompanhamos as regulamenta\u00e7\u00f5es e normas de seguran\u00e7a em constante evolu\u00e7\u00e3o para garantir que sua empresa esteja sempre em conformidade com as leis e regulamentos vigentes.<\/p><p>Investiga\u00e7\u00e3o de Acidentes : Em caso de acidentes, nossa equipe especializada conduz investiga\u00e7\u00f5es realizadas para determinar as causas ra\u00edzes e evitar recorr\u00eancias.<\/p><p>Consultoria Especializada : Estamos \u00e0 disposi\u00e7\u00e3o para fornecer consultoria personalizada e orienta\u00e7\u00e3o estrat\u00e9gica para melhorar continuamente a seguran\u00e7a em sua organiza\u00e7\u00e3o.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-030173e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"030173e\" data-element_type=\"section\" data-e-type=\"section\" id=\"services\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3521218\" data-id=\"3521218\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-205e7c0 elementor-widget elementor-widget-heading\" data-id=\"205e7c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Servi\u00e7os<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0955827 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"0955827\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-55b3a09 elementor-invisible\" data-id=\"55b3a09\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d271a76 content-align-cta-center elementor-widget elementor-widget-eael-cta-box\" data-id=\"d271a76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-cta-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"eael-call-to-action cta-basic bg-lite cta-preset-1\">\n        <h2 class=\"title eael-cta-heading\">Seguran\u00e7a do Trabalho<\/h2><p style=\"text-align: left\">A Isafety Engenharia se destaca por oferecer uma ampla gama de servi\u00e7os, demonstrando estar completamente capacitada para enfrentar os desafios apresentados por nossos clientes. Nosso compromisso \u00e9 fornecer solu\u00e7\u00f5es pr\u00e1ticas, totalmente adaptadas \u00e0s necessidades individuais de cada cliente, sempre com uma abordagem na economia de custos.<\/p><a href=\"https:\/\/isafetyengenharia.com\/home\/servicos\/\" target=\"_blank\" class=\"cta-button cta-preset-1  effect-1\">Ver servi\u00e7os oferecidos<\/a>\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e04c803 elementor-invisible\" data-id=\"e04c803\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36e6431 content-align-cta-center elementor-widget elementor-widget-eael-cta-box\" data-id=\"36e6431\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-cta-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"eael-call-to-action cta-basic bg-lite cta-preset-1\">\n        <h2 class=\"title eael-cta-heading\">Meio Ambiente<\/h2><p>Compreendemos que a gest\u00e3o eficaz dos requisitos ambientais exige a qualifica\u00e7\u00e3o e a expertise dos profissionais envolvidos. Estamos comprometidos em fornecer solu\u00e7\u00f5es que n\u00e3o apenas atendam aos requisitos ambientais, mas tamb\u00e9m agreguem valor aos seus clientes, garantindo a satisfa\u00e7\u00e3o de todas as partes envolvidas, pois possu\u00edmos a paix\u00e3o e o comprometimento com a preserva\u00e7\u00e3o do meio ambiente e a excel\u00eancia no atendimento ao cliente.<\/p><a href=\"https:\/\/isafetyengenharia.com\/home\/servicos\/\" target=\"_blank\" class=\"cta-button cta-preset-1  effect-1\">Ver servi\u00e7os oferecidos<\/a>\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-bc72ad0 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"bc72ad0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-942a742 elementor-invisible\" data-id=\"942a742\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a29656f content-align-cta-center elementor-widget elementor-widget-eael-cta-box\" data-id=\"a29656f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-cta-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"eael-call-to-action cta-basic bg-lite cta-preset-1\">\n        <h2 class=\"title eael-cta-heading\">Servi\u00e7os com Drone<\/h2><p>Os servi\u00e7os oferecidos por drones abrangem uma ampla gama de atividades, destacando-se a capacidade de mapear extensas \u00e1reas, realizar an\u00e1lises detalhadas de estruturas, capturar imagens de equipamentos em locais de dif\u00edcil acesso, al\u00e9m de realizar inspe\u00e7\u00f5es minuciosas em diversas estruturas e equipamentos. Esse conjunto de aplica\u00e7\u00f5es ilustra a simplicidade dessa crescente tecnologia.<\/p><a href=\"https:\/\/isafetyengenharia.com\/home\/servicos\/\" target=\"_blank\" class=\"cta-button cta-preset-1  effect-1\">Ver servi\u00e7os oferecidos<\/a>\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-da3a911 elementor-invisible\" data-id=\"da3a911\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d30da69 content-align-cta-center elementor-widget elementor-widget-eael-cta-box\" data-id=\"d30da69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-cta-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"eael-call-to-action cta-basic bg-lite cta-preset-1\">\n        <h2 class=\"title eael-cta-heading\">Linhas de Vida<\/h2><p>As linhas de vida desempenham um papel crucial na prote\u00e7\u00e3o dos trabalhadores envolvidos em atividades realizadas em altura. A ISAFETY Engenharia assume a responsabilidade de conceber, implementar e zelar pela manuten\u00e7\u00e3o dessas estruturas fundamentais.<\/p><a href=\"https:\/\/isafetyengenharia.com\/home\/servicos\/\" target=\"_blank\" class=\"cta-button cta-preset-1  effect-1\">Ver servi\u00e7os oferecidos<\/a>\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4da8a3d elementor-section-full_width elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-phone elementor-section-height-default elementor-section-height-default\" data-id=\"4da8a3d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b8055c2\" data-id=\"b8055c2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a78c877 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a78c877\" data-element_type=\"section\" data-e-type=\"section\" id=\"clientes\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-247bc26\" data-id=\"247bc26\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd1319f elementor-widget elementor-widget-heading\" data-id=\"bd1319f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Clientes<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2aa1788 gallery-spacing-custom elementor-invisible elementor-widget elementor-widget-image-gallery\" data-id=\"2aa1788\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-1' class='gallery galleryid-4447 gallery-columns-5 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"223\" src=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/12\/grupo-petropolis-vagas-de-emprego-oportunidades-e1703617116828-768x223.png\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/12\/grupo-petropolis-vagas-de-emprego-oportunidades-e1703617116828-768x223.png 768w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/12\/grupo-petropolis-vagas-de-emprego-oportunidades-e1703617116828-300x87.png 300w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/12\/grupo-petropolis-vagas-de-emprego-oportunidades-e1703617116828.png 918w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"253\" src=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/12\/suzano-logo-e1703617146235.png\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/12\/suzano-logo-e1703617146235.png 768w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/12\/suzano-logo-e1703617146235-300x99.png 300w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"287\" src=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/logo-embraer-2048-768x287.png\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/logo-embraer-2048-768x287.png 768w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/logo-embraer-2048-300x112.png 300w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/logo-embraer-2048-1024x382.png 1024w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/logo-embraer-2048-1536x573.png 1536w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/logo-embraer-2048.png 2048w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"202\" src=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/logo-fibria.png\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/logo-fibria.png 640w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/logo-fibria-300x95.png 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"241\" src=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/12\/x5-logo-768x241.png\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/12\/x5-logo-768x241.png 768w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/12\/x5-logo-300x94.png 300w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/12\/x5-logo-1024x322.png 1024w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/12\/x5-logo-1536x482.png 1536w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/12\/x5-logo.png 1538w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"204\" height=\"108\" src=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/FASE.png\" class=\"attachment-medium_large size-medium_large\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"164\" src=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/hs-emp-branding-image-data_-768x164.png\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/hs-emp-branding-image-data_-768x164.png 768w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/hs-emp-branding-image-data_-300x64.png 300w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/hs-emp-branding-image-data_-1024x219.png 1024w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/hs-emp-branding-image-data_.png 1170w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"226\" height=\"109\" src=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/dqo-construtora.png\" class=\"attachment-medium_large size-medium_large\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"411\" src=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/logo-heineken-e1703617269636-768x411.png\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/logo-heineken-e1703617269636-768x411.png 768w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/logo-heineken-e1703617269636-300x161.png 300w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/logo-heineken-e1703617269636.png 1000w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"171\" src=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/X5-COMPANY.png\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/X5-COMPANY.png 366w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/X5-COMPANY-300x140.png 300w\" sizes=\"(max-width: 366px) 100vw, 366px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"432\" src=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/Imerys-768x432.png\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/Imerys-768x432.png 768w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/Imerys-300x169.png 300w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/Imerys.png 960w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"215\" src=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/gran-sapore.png\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/gran-sapore.png 512w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/gran-sapore-300x126.png 300w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"150\" src=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/logo_latecoere_400x150_acf_cropped.png\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/logo_latecoere_400x150_acf_cropped.png 400w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/logo_latecoere_400x150_acf_cropped-300x113.png 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"493\" src=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/Logo-Preta-2.png\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/Logo-Preta-2.png 600w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/Logo-Preta-2-300x247.png 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"272\" src=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/ti-auto-768x272.png\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/ti-auto-768x272.png 768w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/ti-auto-300x106.png 300w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/ti-auto.png 1024w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"465\" height=\"292\" src=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/iana2-alimentos-hd-png-download.png\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/iana2-alimentos-hd-png-download.png 465w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/iana2-alimentos-hd-png-download-300x188.png 300w\" sizes=\"(max-width: 465px) 100vw, 465px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"86\" src=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/logo-inylbra-pq1-300x86-1.png\" class=\"attachment-medium_large size-medium_large\" alt=\"\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"345\" height=\"194\" src=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/petybon-logo.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/petybon-logo.jpg 345w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/petybon-logo-300x169.jpg 300w\" sizes=\"(max-width: 345px) 100vw, 345px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"390\" src=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/msa-brasil.png\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/msa-brasil.png 600w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/msa-brasil-300x195.png 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"210\" src=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/logo_f-grama.png\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/logo_f-grama.png 600w, https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2020\/12\/logo_f-grama-300x105.png 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b2f0eec elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b2f0eec\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1b6730a\" data-id=\"1b6730a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b3e87a elementor-widget elementor-widget-heading\" data-id=\"3b3e87a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contato<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-015c9f7 elementor-section-content-middle elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"015c9f7\" data-element_type=\"section\" data-e-type=\"section\" id=\"contact\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d1a8c64\" data-id=\"d1a8c64\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1707918 elementor-widget elementor-widget-heading\" data-id=\"1707918\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Preencha o formul\u00e1rio e envie sua mensagem.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d2dae9 elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"1d2dae9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\" aria-label=\"New Form\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"4447\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"1d2dae9\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"iSafety Engenharia - Treinamentos, seguran\u00e7a do trabalho e consultorias.\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"4447\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tNome\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Nome\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-field_a592724 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_a592724\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tTelefone\/ WhatsApp\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[field_a592724]\" id=\"form-field-field_a592724\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Apenas n\u00fameros e caracteres de telefone (#, -, *, etc.) s\u00e3o aceitos.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Email\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tMensagem\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\" placeholder=\"Mensagem\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-paper-plane\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Enviar<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-63d6258\" data-id=\"63d6258\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e3c4a88 elementor-widget elementor-widget-text-editor\" data-id=\"e3c4a88\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: justify;\">Entre em contato e solicite um or\u00e7amento sem compromisso. <strong>Profissionalismo e experi\u00eancia em servi\u00e7os personalizados conforme a necessidade de cada cliente!<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8286375 elementor-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"8286375\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">(12) 98181-0181<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-envelope\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">comercial@isafetyengenharia.com<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Endere\u00e7o: Rua Antonio Afonso 559  - Centro - Jacare\u00ed\/SP CEP: 12327-270.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a727052 elementor-shape-rounded elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"a727052\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-b977f7f\" href=\"https:\/\/www.instagram.com\/isafetyengenharia\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook-f elementor-repeater-item-030f11b\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook-f<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook-f\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin-in elementor-repeater-item-9c6b4b3\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin-in<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-linkedin-in\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-76cc05d elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"76cc05d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bd26079\" data-id=\"bd26079\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Engenharia de Seguran\u00e7a do TrabalhoEngenharia a Servi\u00e7o da VidaVer servi\u00e7osMeio AmbienteEspecialistas em projetos de meio ambiente.Ver servi\u00e7osTreinamentos Treinamentos T\u00e9cnicos e normativos de qualidade.Ver servi\u00e7osDrone SpecialistUtiliza\u00e7\u00e3o de drones para fiscaliza\u00e7\u00e3o e monitoramentos de projetos e empresas.Ver servi\u00e7os Previous slide Next slide N\u00d3S CUIDAMOS DA SUA SEGURAN\u00c7A NO TRABALHO\u200b Atuamos em diversos segmentos, como obras, empresas, \u00e1reas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5471,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_joinchat":[],"footnotes":""},"class_list":["post-4447","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>iSafety Engenharia - Treinamentos, seguran\u00e7a do trabalho e consultorias.<\/title>\n<meta name=\"description\" content=\"Descubra solu\u00e7\u00f5es inovadoras em seguran\u00e7a do trabalho e engenharia na iSafety Engenharia. Nossa expertise abrange consultoria, treinamentos e tecnologias para promover ambientes laborais seguros. Conhe\u00e7a nossos servi\u00e7os.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/isafetyengenharia.com\/home\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"iSafety Engenharia - Treinamentos, seguran\u00e7a do trabalho e consultorias.\" \/>\n<meta property=\"og:description\" content=\"Descubra solu\u00e7\u00f5es inovadoras em seguran\u00e7a do trabalho e engenharia na iSafety Engenharia. Nossa expertise abrange consultoria, treinamentos e tecnologias para promover ambientes laborais seguros. Conhe\u00e7a nossos servi\u00e7os.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/isafetyengenharia.com\/home\/\" \/>\n<meta property=\"og:site_name\" content=\"iSafety Engenharia\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-26T20:00:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/10\/a05b73d6-2e29-4c6c-8d0e-10ec24588013.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/isafetyengenharia.com\/home\/\",\"url\":\"https:\/\/isafetyengenharia.com\/home\/\",\"name\":\"iSafety Engenharia - Treinamentos, seguran\u00e7a do trabalho e consultorias.\",\"isPartOf\":{\"@id\":\"https:\/\/isafetyengenharia.com\/home\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/isafetyengenharia.com\/home\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/isafetyengenharia.com\/home\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/10\/a05b73d6-2e29-4c6c-8d0e-10ec24588013.jpg\",\"datePublished\":\"2020-08-11T11:04:19+00:00\",\"dateModified\":\"2023-12-26T20:00:16+00:00\",\"description\":\"Descubra solu\u00e7\u00f5es inovadoras em seguran\u00e7a do trabalho e engenharia na iSafety Engenharia. Nossa expertise abrange consultoria, treinamentos e tecnologias para promover ambientes laborais seguros. Conhe\u00e7a nossos servi\u00e7os.\",\"breadcrumb\":{\"@id\":\"https:\/\/isafetyengenharia.com\/home\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/isafetyengenharia.com\/home\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/isafetyengenharia.com\/home\/#primaryimage\",\"url\":\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/10\/a05b73d6-2e29-4c6c-8d0e-10ec24588013.jpg\",\"contentUrl\":\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/10\/a05b73d6-2e29-4c6c-8d0e-10ec24588013.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/isafetyengenharia.com\/home\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/isafetyengenharia.com\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"iSatefy Engenharia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/isafetyengenharia.com\/home\/#website\",\"url\":\"https:\/\/isafetyengenharia.com\/home\/\",\"name\":\"iSafety Engenharia\",\"description\":\"Servi\u00e7os de Engenharia e Meio Ambiente\",\"publisher\":{\"@id\":\"https:\/\/isafetyengenharia.com\/home\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/isafetyengenharia.com\/home\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/isafetyengenharia.com\/home\/#organization\",\"name\":\"iSafety Engenharia\",\"url\":\"https:\/\/isafetyengenharia.com\/home\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/isafetyengenharia.com\/home\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/12\/ISAFETY-LOGO-NOVO.png\",\"contentUrl\":\"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/12\/ISAFETY-LOGO-NOVO.png\",\"width\":3816,\"height\":1310,\"caption\":\"iSafety Engenharia\"},\"image\":{\"@id\":\"https:\/\/isafetyengenharia.com\/home\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/isafetyengenharia\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"iSafety Engenharia - Treinamentos, seguran\u00e7a do trabalho e consultorias.","description":"Descubra solu\u00e7\u00f5es inovadoras em seguran\u00e7a do trabalho e engenharia na iSafety Engenharia. Nossa expertise abrange consultoria, treinamentos e tecnologias para promover ambientes laborais seguros. Conhe\u00e7a nossos servi\u00e7os.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/isafetyengenharia.com\/home\/","og_locale":"pt_BR","og_type":"article","og_title":"iSafety Engenharia - Treinamentos, seguran\u00e7a do trabalho e consultorias.","og_description":"Descubra solu\u00e7\u00f5es inovadoras em seguran\u00e7a do trabalho e engenharia na iSafety Engenharia. Nossa expertise abrange consultoria, treinamentos e tecnologias para promover ambientes laborais seguros. Conhe\u00e7a nossos servi\u00e7os.","og_url":"https:\/\/isafetyengenharia.com\/home\/","og_site_name":"iSafety Engenharia","article_modified_time":"2023-12-26T20:00:16+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/10\/a05b73d6-2e29-4c6c-8d0e-10ec24588013.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/isafetyengenharia.com\/home\/","url":"https:\/\/isafetyengenharia.com\/home\/","name":"iSafety Engenharia - Treinamentos, seguran\u00e7a do trabalho e consultorias.","isPartOf":{"@id":"https:\/\/isafetyengenharia.com\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/isafetyengenharia.com\/home\/#primaryimage"},"image":{"@id":"https:\/\/isafetyengenharia.com\/home\/#primaryimage"},"thumbnailUrl":"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/10\/a05b73d6-2e29-4c6c-8d0e-10ec24588013.jpg","datePublished":"2020-08-11T11:04:19+00:00","dateModified":"2023-12-26T20:00:16+00:00","description":"Descubra solu\u00e7\u00f5es inovadoras em seguran\u00e7a do trabalho e engenharia na iSafety Engenharia. Nossa expertise abrange consultoria, treinamentos e tecnologias para promover ambientes laborais seguros. Conhe\u00e7a nossos servi\u00e7os.","breadcrumb":{"@id":"https:\/\/isafetyengenharia.com\/home\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/isafetyengenharia.com\/home\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/isafetyengenharia.com\/home\/#primaryimage","url":"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/10\/a05b73d6-2e29-4c6c-8d0e-10ec24588013.jpg","contentUrl":"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/10\/a05b73d6-2e29-4c6c-8d0e-10ec24588013.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/isafetyengenharia.com\/home\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/isafetyengenharia.com\/home\/"},{"@type":"ListItem","position":2,"name":"iSatefy Engenharia"}]},{"@type":"WebSite","@id":"https:\/\/isafetyengenharia.com\/home\/#website","url":"https:\/\/isafetyengenharia.com\/home\/","name":"iSafety Engenharia","description":"Servi\u00e7os de Engenharia e Meio Ambiente","publisher":{"@id":"https:\/\/isafetyengenharia.com\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/isafetyengenharia.com\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/isafetyengenharia.com\/home\/#organization","name":"iSafety Engenharia","url":"https:\/\/isafetyengenharia.com\/home\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/isafetyengenharia.com\/home\/#\/schema\/logo\/image\/","url":"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/12\/ISAFETY-LOGO-NOVO.png","contentUrl":"https:\/\/isafetyengenharia.com\/home\/wp-content\/uploads\/2023\/12\/ISAFETY-LOGO-NOVO.png","width":3816,"height":1310,"caption":"iSafety Engenharia"},"image":{"@id":"https:\/\/isafetyengenharia.com\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/isafetyengenharia\/"]}]}},"_links":{"self":[{"href":"https:\/\/isafetyengenharia.com\/home\/wp-json\/wp\/v2\/pages\/4447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/isafetyengenharia.com\/home\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/isafetyengenharia.com\/home\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/isafetyengenharia.com\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/isafetyengenharia.com\/home\/wp-json\/wp\/v2\/comments?post=4447"}],"version-history":[{"count":390,"href":"https:\/\/isafetyengenharia.com\/home\/wp-json\/wp\/v2\/pages\/4447\/revisions"}],"predecessor-version":[{"id":5659,"href":"https:\/\/isafetyengenharia.com\/home\/wp-json\/wp\/v2\/pages\/4447\/revisions\/5659"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/isafetyengenharia.com\/home\/wp-json\/wp\/v2\/media\/5471"}],"wp:attachment":[{"href":"https:\/\/isafetyengenharia.com\/home\/wp-json\/wp\/v2\/media?parent=4447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}